{"id":48410,"date":"2023-07-27T19:38:32","date_gmt":"2023-07-27T19:38:32","guid":{"rendered":"https:\/\/economiasa.com.br\/?p=48410"},"modified":"2023-07-27T19:38:32","modified_gmt":"2023-07-27T19:38:32","slug":"empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria","status":"publish","type":"post","link":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/","title":{"rendered":"Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria"},"content":{"rendered":"<p>O empres\u00e1rio carioca Pierre Leal, conhecido por suas contribui\u00e7\u00f5es no mundo do entretenimento, ir\u00e1 a comemorar seu anivers\u00e1rio em grande estilo na famosa boate London Ginkeria. Pierre \u00e9 um nome muito respeitado na cena noturna do Rio de Janeiro, sendo socio das saudosas Via Show em S\u00e3o Jo\u00e3o de Meriti, na baixada fluminense, Olimpo, e West Show, que deixou uma marca inesquec\u00edvel em Campo Grande.<\/p>\n<p>A London Ginkeria, a mais nova empreitada de Pierre Leal, \u00e9 um espa\u00e7o sofisticado e moderno que rapidamente se tornou um dos destinos mais badalados da cidade. Localizada no cora\u00e7\u00e3o de Campo Grande, a casa noturna \u00e9 conhecida por suas festas animadas, ambiente acolhedor e uma programa\u00e7\u00e3o variada que atrai p\u00fablicos de diferentes idades e gostos.<\/p>\n<p>Para comemorar seu anivers\u00e1rio em grande estilo, Pierre est\u00e1 preparando uma festa Remember para homenagear suas antigas casas de show, o evento ser\u00e1 na London Ginkeria, e contar\u00e1 com v\u00e1rias atra\u00e7\u00f5es especiais, prometendo ser uma noite de celebra\u00e7\u00e3o, alegria e muita divers\u00e3o.<\/p>\n<p>Entre as atra\u00e7\u00f5es est\u00e3o os funkeiros Marcio G, Menor do Chapa e Manda V, trazendo aos palcos sucessos das antigas. Animando a pista ter\u00e1 furac\u00e3o 2000 e Via Show Digital<\/p>\n<p>Sobre Pierre Leal: Pierre Leal \u00e9 um empres\u00e1rio carioca renomado no setor do entretenimento. Com experi\u00eancia na gest\u00e3o de casas noturnas, ele se destaca por criar espa\u00e7os que oferecem experi\u00eancias \u00fanicas ao p\u00fablico. Al\u00e9m de ser o propriet\u00e1rio da saudosa West Show, Pierre \u00e9 o vision\u00e1rio por tr\u00e1s da London Ginkeria, uma das mais conceituadas boates do Rio de Janeiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O empres\u00e1rio carioca Pierre Leal, conhecido por suas contribui\u00e7\u00f5es no mundo do entretenimento, ir\u00e1 a comemorar seu anivers\u00e1rio em grande estilo na&#8230;<\/p>\n","protected":false},"author":3,"featured_media":48411,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"ppma_author":[13250],"class_list":{"0":"post-48410","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria - Economia S\/A<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria - Economia S\/A\" \/>\n<meta property=\"og:description\" content=\"O empres\u00e1rio carioca Pierre Leal, conhecido por suas contribui\u00e7\u00f5es no mundo do entretenimento, ir\u00e1 a comemorar seu anivers\u00e1rio em grande estilo na...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/\" \/>\n<meta property=\"og:site_name\" content=\"Economia S\/A\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-27T19:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-16.21.33.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"530\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jairo Rodrigues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jairo Rodrigues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/\"},\"author\":{\"name\":\"Jairo Rodrigues\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/c4e43d28ad57f916afdad2d90567c101\"},\"headline\":\"Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria\",\"datePublished\":\"2023-07-27T19:38:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/\"},\"wordCount\":289,\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-16.21.33.jpeg\",\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/\",\"url\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/\",\"name\":\"Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria - Economia S\/A\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-16.21.33.jpeg\",\"datePublished\":\"2023-07-27T19:38:32+00:00\",\"author\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/c4e43d28ad57f916afdad2d90567c101\"},\"breadcrumb\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#primaryimage\",\"url\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-16.21.33.jpeg\",\"contentUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-16.21.33.jpeg\",\"width\":530,\"height\":377},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/economiasa.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\",\"url\":\"https:\/\/economiasa.com.br\/blog\/\",\"name\":\"Economia S\/A\",\"description\":\"Ler faz bem para os neg\u00f3cios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/c4e43d28ad57f916afdad2d90567c101\",\"name\":\"Jairo Rodrigues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/846ba13a3a5e3b5e4ba7e1997a7783ca4c491769262288ea7f505de550c663f8?s=96&d=mm&r=g00ff928a5d36845983415735242bcb75\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/846ba13a3a5e3b5e4ba7e1997a7783ca4c491769262288ea7f505de550c663f8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/846ba13a3a5e3b5e4ba7e1997a7783ca4c491769262288ea7f505de550c663f8?s=96&d=mm&r=g\",\"caption\":\"Jairo Rodrigues\"},\"url\":\"https:\/\/economiasa.com.br\/blog\/author\/jairo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria - Economia S\/A","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/","og_locale":"pt_BR","og_type":"article","og_title":"Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria - Economia S\/A","og_description":"O empres\u00e1rio carioca Pierre Leal, conhecido por suas contribui\u00e7\u00f5es no mundo do entretenimento, ir\u00e1 a comemorar seu anivers\u00e1rio em grande estilo na...","og_url":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/","og_site_name":"Economia S\/A","article_published_time":"2023-07-27T19:38:32+00:00","og_image":[{"width":530,"height":377,"url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-16.21.33.jpeg","type":"image\/jpeg"}],"author":"Jairo Rodrigues","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jairo Rodrigues","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#article","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/"},"author":{"name":"Jairo Rodrigues","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/c4e43d28ad57f916afdad2d90567c101"},"headline":"Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria","datePublished":"2023-07-27T19:38:32+00:00","mainEntityOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/"},"wordCount":289,"image":{"@id":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-16.21.33.jpeg","articleSection":["News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/","url":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/","name":"Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria - Economia S\/A","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#primaryimage"},"image":{"@id":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-16.21.33.jpeg","datePublished":"2023-07-27T19:38:32+00:00","author":{"@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/c4e43d28ad57f916afdad2d90567c101"},"breadcrumb":{"@id":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#primaryimage","url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-16.21.33.jpeg","contentUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-16.21.33.jpeg","width":530,"height":377},{"@type":"BreadcrumbList","@id":"https:\/\/economiasa.com.br\/blog\/empresario-carioca-pierre-leal-celebra-aniversario-com-grandiosa-festa-na-london-ginkeria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/economiasa.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Empres\u00e1rio carioca Pierre Leal celebra anivers\u00e1rio com grandiosa festa na London Ginkeria"}]},{"@type":"WebSite","@id":"https:\/\/economiasa.com.br\/blog\/#website","url":"https:\/\/economiasa.com.br\/blog\/","name":"Economia S\/A","description":"Ler faz bem para os neg\u00f3cios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/c4e43d28ad57f916afdad2d90567c101","name":"Jairo Rodrigues","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/846ba13a3a5e3b5e4ba7e1997a7783ca4c491769262288ea7f505de550c663f8?s=96&d=mm&r=g00ff928a5d36845983415735242bcb75","url":"https:\/\/secure.gravatar.com\/avatar\/846ba13a3a5e3b5e4ba7e1997a7783ca4c491769262288ea7f505de550c663f8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/846ba13a3a5e3b5e4ba7e1997a7783ca4c491769262288ea7f505de550c663f8?s=96&d=mm&r=g","caption":"Jairo Rodrigues"},"url":"https:\/\/economiasa.com.br\/blog\/author\/jairo\/"}]}},"authors":[{"term_id":13250,"user_id":3,"is_guest":0,"slug":"jairo","display_name":"Jairo Rodrigues","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/846ba13a3a5e3b5e4ba7e1997a7783ca4c491769262288ea7f505de550c663f8?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/48410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/comments?post=48410"}],"version-history":[{"count":0,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/48410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media\/48411"}],"wp:attachment":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media?parent=48410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/categories?post=48410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/tags?post=48410"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/ppma_author?post=48410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}