{"id":49062,"date":"2023-08-21T16:29:24","date_gmt":"2023-08-21T16:29:24","guid":{"rendered":"https:\/\/economiasa.com.br\/?p=49062"},"modified":"2023-08-21T16:29:24","modified_gmt":"2023-08-21T16:29:24","slug":"gito-sales-e-dany-maya-criam-o-alquemy","status":"publish","type":"post","link":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/","title":{"rendered":"Gito Sales e Dany Maya criam o ALQUEMY"},"content":{"rendered":"<p>Em perfeita harmonia, acontece um encontro de vozes, energias musicais e personas fora dar caixa.<\/p>\n<p>Gito Sales e Dani Maya se re\u00fanem nesse projeto para mostrar ao mundo o charme da Brazilian Jazz Bossa Music, somando uma pitada apimentada de sonoridades e ilustra\u00e7\u00f5es. O projeto promete surpreender por sua simplicidade requintada e sua pegada bem org\u00e2nica nas interpreta\u00e7\u00f5es. Uma hora e meia de releituras de cl\u00e1ssicos da m\u00fasica com a mesma ess\u00eancia de\u00a0 suas concep\u00e7\u00f5es mas um novo conceito. Gito, com sua larga experi\u00eancia no mundo musical, como int\u00e9rprete, compositor, instrumentista, arranjador e produtor fonogr\u00e1fico dirige este espet\u00e1culo com suas refer\u00eancias mais pop e rock e jazz, enquanto Dani com sua hist\u00f3ria que transita entre a bossa nova o jazz, o samba, a world music e a MPB o complementa dando vida a um conceito hibrido, elegante e ousado. Imperd\u00edvel! Vale a pena conferir!<\/p>\n<figure class=\"wp-block-image aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22694 aligncenter\" src=\"https:\/\/viajarsa.com.br\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.56.jpeg\" alt=\"\" width=\"305\" height=\"258\" \/><\/figure>\n<p><strong>DANI MAYA<\/strong><\/p>\n<p>Carioca, menina do bairro de laranjeiras. Col\u00e9gio de freiras. Forma\u00e7\u00e3o em administra\u00e7\u00e3o de empresas e MBA em Marketing e Gest\u00e3o Empresarial. Tudo a levava para uma carreira corporativa e assim foi por muitos anos at\u00e9 que uma dia, ela se mudou para uma ilha l\u00fadica na Barra da Tijuca e ali tudo mudaria\u2026 Em uma tarde, cantarolando entre vizinhos, seu amigo e vizinho Nonato Buzar a olhou e disse \u201cmenina.. vc nasceu pra cantar e n\u00e3o sabe ainda e lhe colocou em seu palco\u201d.<\/p>\n<p>Dani Maya iniciou sua carreira cantando Bossa Nova junto a grandes mestres como Nonato Buzar, Pery Ribeiro e Tiberio Gaspar e at\u00e9 hoje participa de projetos de bossa nova produzidos por Raymundo Bittencourt e Roberto Menescal. Atra\u00edda e praticamente capturada pelo samba de raiz acabou participando de grandes rodas tradicionais como Curtume Carioca, Bo\u00eamios de Iraja, Cacique de Ramos, Renascen\u00e7a, Quintal do Zeca entre outras e dividindo o palco com \u00eddolos como Almir Guineto, Jorge Aragao, Arlindo Cruz, Quintal do Zeca e v\u00e1rios idolos.<\/p>\n<p>Fez parte do grupo Batacoto e ao ser m\u00e3e nessa \u00e9poca, acabou se afastando da m\u00fasica e dos palcos mas nunca deixou de compor. Retomando sua carreira ano passado com o lan\u00e7amento de um disco internacional cantando cl\u00e1ssicos do Tom Jobim em ingl\u00eas, a chama se reascendeu. Este ano est\u00e1 lan\u00e7ando seu primeiro disco autoral VC canta OQ? que passeia por ritmos diversos da MPB e traz mensagens positivas e de comportamento com a proposta de ser sem r\u00f3tulos, misturando ritmos e sonoridades. 3 discos gravados, sendo que o primeiro no Brasil est\u00e1 sendo lan\u00e7ado agora apresentando sua carreira. V\u00eddeo clips produzidos e editados por ela mesma, alguns com seu pr\u00f3prio celular.\u00a0 Sempre com uma mensagem hibrida de comportamento em suas letras e tecnologia em sua apresenta\u00e7\u00e3o gr\u00e1fica e visual (seu outro lado como modelista 3D e developer de tecnologia por profiss\u00e3o) ela busca a uni\u00e3o da ess\u00eancia do presente com a tend\u00eancia do futuro para que o org\u00e2nico e o digital se encontrem com harmonia.<\/p>\n<p><strong>GITO SALES<\/strong><\/p>\n<p>S\u00e9rgio Herberto Sales da Cunha Mello (Gito Sales), nascido no Rio de Janeiro em 14 de maio de 1963,,come\u00e7ou a trabalhar aos quatro anos de idade como modelo infantil, usando o nome de \u201cSergito\u201d. Aos oito anos come\u00e7ou a tocar viol\u00e3o e com quatorze anos se tornou profissional, participando no disco \u201cPaladar\u201d, de Herberto Filho, produzido por Cl\u00e1udio Cartier. Neste per\u00edodo<\/p>\n<p>come\u00e7ou a assinar \u201cGito Sales\u201d. Bacharel em Administra\u00e7\u00e3o, com p\u00f3s gradua\u00e7\u00e3o em Marketing Cultural, iniciou sua carreira tocando bossa nova e levou para a guitarra toda esta influ\u00eancia harm\u00f4nica, tendo o grande mentor o mestre Toninho Horta, Rosinha de Valen\u00e7a e Manoel da Concei\u00e7\u00e3o (M\u00e3o de Vaca).Seu primeiro trabalho fonogr\u00e1fico foi em 1981, como guitarrista e vocalista do LP \u201cPaladar\u201d, de Herberto Filho. Em 1983, gravou seu primeiro compacto simples independente com duas faixas:<\/p>\n<p>\u201cEu Sou Mais Eu\u201d (Arnaldo Brand\u00e3o) e \u201cAcredite Se Quiser\u201d (Prentice).Ainda na d\u00e9cada de 80 integrou, como guitarrista, juntamente com Davi Morais (guitarras), Z\u00e9 Ricardo (vocal), Modesto (baixo) e Linhos (bateria), a banda \u201cFibra de Vida\u201d, com a qual gravou um LP lan\u00e7ado pela Warner.De 1990 a 1992, como violonista, guitarrista e vocalista, fez parte da banda Fantasmas, montada por ele, com os integrantes: Andr\u00e9 Gatti (guitarra e backing vocal), Marcus Rey (bateria e vocais) Karina Hoffter (voz), e Emerson Mardhine (baixo e vocais), e participa\u00e7\u00e3o especial de Milton Guedes. Com a banda gravou, em 1990, o disco \u201cFantasmas\u201d, com a regrava\u00e7\u00e3o da m\u00fasica \u201cOvelha Negra\u201d (Rita Lee), que fez parte da trilha sonora da novela \u201cMulheres de areia\u201d (TV Globo), al\u00e9m de ter sido contemplado, em 1992, com o \u201cPr\u00eamio Sharp\u201d, na categoria \u201cMelhor Grupo de M\u00fasica Popular\u201d.<\/p>\n<p>Em 1998, participou da dupla pop V\u00eaennix, como guitarrista, violonista, vocalista, produtor e diretor, ao lado de Vin\u00edcius Ottoni (voz e teclados).No novo mil\u00eanio (2000) voltou \u00e0 cena independente de Bras\u00edlia, participando de projetos junto a grandes nomes da m\u00fasica popular brasileira. Em 2005 iniciou um novo trabalho chamado \u201cIndepend\u00eancia J\u00e1\u201d, com coprodu\u00e7\u00e3o de Vinny e Roberto Lly. Fez turn\u00eas pelo Brasil, com foco no movimento independente, durante quase tr\u00eas anos.Depois foi para Nova Iorque, onde fez diversas apresenta\u00e7\u00f5es no Blue Notes, Zinck Bar, entre outros. Foi convidado pela Gravadora Virgin para um pr\u00e9-contrato, onde gravaria cl\u00e1ssicos do Brazilian Jazz.Em 2012, j\u00e1 em Barcelona, teve indica\u00e7\u00e3o para o Grammy pela produ\u00e7\u00e3o da banda espanhola Lagarto Amarillo.Em 2015, lan\u00e7a o EP com a turn\u00ea \u201cTempo ao Tempo\u201d comemorando 30 anos de carreira e sua volta ap\u00f3s anos a Warner Chappell Music como compositor tendo uma nova releitura da Rita Lee e Roberto de Carvalho \u201cCoisas de Casal\u201d somente gravada pela Banda Radio Taxi e 3 m\u00fasicas in\u00e9ditas de sua autoria \u201cN\u00e3o Me Diga N\u00e3o\u201d, \u201cAnjo\u201d e \u201cTempo ao Tempo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em perfeita harmonia, acontece um encontro de vozes, energias musicais e personas fora dar caixa. Gito Sales e Dani Maya se re\u00fanem&#8230;<\/p>\n","protected":false},"author":2,"featured_media":49063,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"ppma_author":[13249],"class_list":{"0":"post-49062","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-viral"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gito Sales e Dany Maya criam o ALQUEMY - Economia S\/A<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gito Sales e Dany Maya criam o ALQUEMY - Economia S\/A\" \/>\n<meta property=\"og:description\" content=\"Em perfeita harmonia, acontece um encontro de vozes, energias musicais e personas fora dar caixa. Gito Sales e Dani Maya se re\u00fanem...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/\" \/>\n<meta property=\"og:site_name\" content=\"Economia S\/A\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-21T16:29:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.55.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"608\" \/>\n\t<meta property=\"og:image:height\" content=\"413\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"HERNANE OLIVEIRA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"HERNANE OLIVEIRA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/\"},\"author\":{\"name\":\"HERNANE OLIVEIRA\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/6def2515a5d11b1de9cbbbe9ebe10f75\"},\"headline\":\"Gito Sales e Dany Maya criam o ALQUEMY\",\"datePublished\":\"2023-08-21T16:29:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/\"},\"wordCount\":1019,\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.55.jpeg\",\"articleSection\":[\"Viral\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/\",\"url\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/\",\"name\":\"Gito Sales e Dany Maya criam o ALQUEMY - Economia S\/A\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.55.jpeg\",\"datePublished\":\"2023-08-21T16:29:24+00:00\",\"author\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/6def2515a5d11b1de9cbbbe9ebe10f75\"},\"breadcrumb\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#primaryimage\",\"url\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.55.jpeg\",\"contentUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.55.jpeg\",\"width\":608,\"height\":413},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/economiasa.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gito Sales e Dany Maya criam o ALQUEMY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\",\"url\":\"https:\/\/economiasa.com.br\/blog\/\",\"name\":\"Economia S\/A\",\"description\":\"Ler faz bem para os neg\u00f3cios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/6def2515a5d11b1de9cbbbe9ebe10f75\",\"name\":\"HERNANE OLIVEIRA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/c290b4eb705b462fb1dd4e17118536ede2cd1b474c4afd747ea5c1f3575f7d36?s=96&d=mm&r=gdd85e7e876e7982efaa99829b18cd37e\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c290b4eb705b462fb1dd4e17118536ede2cd1b474c4afd747ea5c1f3575f7d36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c290b4eb705b462fb1dd4e17118536ede2cd1b474c4afd747ea5c1f3575f7d36?s=96&d=mm&r=g\",\"caption\":\"HERNANE OLIVEIRA\"},\"url\":\"https:\/\/economiasa.com.br\/blog\/author\/hernane\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gito Sales e Dany Maya criam o ALQUEMY - Economia S\/A","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/","og_locale":"pt_BR","og_type":"article","og_title":"Gito Sales e Dany Maya criam o ALQUEMY - Economia S\/A","og_description":"Em perfeita harmonia, acontece um encontro de vozes, energias musicais e personas fora dar caixa. Gito Sales e Dani Maya se re\u00fanem...","og_url":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/","og_site_name":"Economia S\/A","article_published_time":"2023-08-21T16:29:24+00:00","og_image":[{"width":608,"height":413,"url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.55.jpeg","type":"image\/jpeg"}],"author":"HERNANE OLIVEIRA","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"HERNANE OLIVEIRA","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#article","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/"},"author":{"name":"HERNANE OLIVEIRA","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/6def2515a5d11b1de9cbbbe9ebe10f75"},"headline":"Gito Sales e Dany Maya criam o ALQUEMY","datePublished":"2023-08-21T16:29:24+00:00","mainEntityOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/"},"wordCount":1019,"image":{"@id":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.55.jpeg","articleSection":["Viral"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/","url":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/","name":"Gito Sales e Dany Maya criam o ALQUEMY - Economia S\/A","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#primaryimage"},"image":{"@id":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.55.jpeg","datePublished":"2023-08-21T16:29:24+00:00","author":{"@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/6def2515a5d11b1de9cbbbe9ebe10f75"},"breadcrumb":{"@id":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#primaryimage","url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.55.jpeg","contentUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-21-at-12.37.55.jpeg","width":608,"height":413},{"@type":"BreadcrumbList","@id":"https:\/\/economiasa.com.br\/blog\/gito-sales-e-dany-maya-criam-o-alquemy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/economiasa.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Gito Sales e Dany Maya criam o ALQUEMY"}]},{"@type":"WebSite","@id":"https:\/\/economiasa.com.br\/blog\/#website","url":"https:\/\/economiasa.com.br\/blog\/","name":"Economia S\/A","description":"Ler faz bem para os neg\u00f3cios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/6def2515a5d11b1de9cbbbe9ebe10f75","name":"HERNANE OLIVEIRA","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c290b4eb705b462fb1dd4e17118536ede2cd1b474c4afd747ea5c1f3575f7d36?s=96&d=mm&r=gdd85e7e876e7982efaa99829b18cd37e","url":"https:\/\/secure.gravatar.com\/avatar\/c290b4eb705b462fb1dd4e17118536ede2cd1b474c4afd747ea5c1f3575f7d36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c290b4eb705b462fb1dd4e17118536ede2cd1b474c4afd747ea5c1f3575f7d36?s=96&d=mm&r=g","caption":"HERNANE OLIVEIRA"},"url":"https:\/\/economiasa.com.br\/blog\/author\/hernane\/"}]}},"authors":[{"term_id":13249,"user_id":2,"is_guest":0,"slug":"hernane","display_name":"HERNANE OLIVEIRA","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/c290b4eb705b462fb1dd4e17118536ede2cd1b474c4afd747ea5c1f3575f7d36?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/49062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/comments?post=49062"}],"version-history":[{"count":0,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/49062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media\/49063"}],"wp:attachment":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media?parent=49062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/categories?post=49062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/tags?post=49062"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/ppma_author?post=49062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}