{"id":58115,"date":"2025-03-27T14:54:40","date_gmt":"2025-03-27T17:54:40","guid":{"rendered":"https:\/\/economiasa.com.br\/blog\/?p=58115"},"modified":"2025-03-27T14:54:41","modified_gmt":"2025-03-27T17:54:41","slug":"bancos-e-fintechs-e-possivel-cooperar-sem-competir","status":"publish","type":"post","link":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/","title":{"rendered":"Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"674\" src=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-1024x674.jpg\" alt=\"\" class=\"wp-image-57763\" srcset=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-1024x674.jpg 1024w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-300x197.jpg 300w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-768x505.jpg 768w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-1536x1011.jpg 1536w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-2048x1348.jpg 2048w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-360x237.jpg 360w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em>Por\u00a0<\/em><a href=\"https:\/\/www.linkedin.com\/in\/franciscoebspereira\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Francisco Pereira<\/em><\/a><em>, CEO da\u00a0<\/em><a href=\"https:\/\/trademaster.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Trademaster<\/em><\/a><em>*<\/em><\/p>\n\n\n\n<p>Nos \u00faltimos anos, o mercado financeiro brasileiro passou por uma transforma\u00e7\u00e3o acelerada, impulsionada pelo surgimento e crescimento das fintechs. O Brasil, hoje, \u00e9 reconhecido como um dos principais polos globais desse tipo de inova\u00e7\u00e3o. Em julho de 2024, de acordo com um relat\u00f3rio do Distrito, o Brasil somava a incr\u00edvel marca de 1.592 fintechs ativas, o que corresponde a 58,7% do total de fintechs da Am\u00e9rica Latina. Este cen\u00e1rio coloca uma quest\u00e3o importante: bancos e fintechs est\u00e3o em competi\u00e7\u00e3o direta ou h\u00e1 espa\u00e7o para coopera\u00e7\u00e3o?<\/p>\n\n\n\n<p>Como executivo da Trademaster, uma empresa que busca conectar o mercado financeiro com novas solu\u00e7\u00f5es tecnol\u00f3gicas, observo de perto o impacto dessa dualidade. \u00c9 natural pensar que bancos tradicionais e fintechs sejam rivais, especialmente quando analisamos o aumento da participa\u00e7\u00e3o dessas startups no mercado de cr\u00e9dito, pagamentos e investimentos, \u00e1reas historicamente dominadas pelos grandes bancos. No entanto, a verdade \u00e9 mais complexa.<\/p>\n\n\n\n<p><strong>O que leva \u00e0 competi\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>Os bancos brasileiros sempre tiveram uma posi\u00e7\u00e3o s\u00f3lida no mercado. Institui\u00e7\u00f5es como Ita\u00fa Unibanco, Bradesco, Banco do Brasil e Caixa Econ\u00f4mica Federal somam uma parcela significativa dos ativos banc\u00e1rios do pa\u00eds. Essa concentra\u00e7\u00e3o de mercado, junto a regulamenta\u00e7\u00f5es r\u00edgidas e altas barreiras de entrada, fez com que os bancos tradicionais dominassem o setor por d\u00e9cadas.<\/p>\n\n\n\n<p>Com a chegada das fintechs, essa hegemonia come\u00e7ou a ser desafiada. Um dos maiores exemplos \u00e9 o Nubank, fundado em 2013, que rapidamente se tornou uma das maiores fintechs do mundo, atingindo mais de 100 milh\u00f5es de clientes em 2024. O que permite esse crescimento acelerado \u00e9 o uso intensivo de tecnologia para criar produtos mais acess\u00edveis e com menos burocracia, algo que os grandes bancos, at\u00e9 pouco tempo atr\u00e1s, n\u00e3o conseguiam oferecer.<\/p>\n\n\n\n<p>Al\u00e9m disso, as fintechs costumam ter uma estrutura mais enxuta e \u00e1gil, o que lhes permite lan\u00e7ar produtos e servi\u00e7os rapidamente, ajustando-se melhor \u00e0s necessidades dos consumidores modernos. Bancos tradicionais, por outro lado, precisam lidar com uma estrutura complexa e pesada, dificultando a inova\u00e7\u00e3o no mesmo ritmo das fintechs. Essa diferen\u00e7a pode criar a percep\u00e7\u00e3o de que estamos diante de uma competi\u00e7\u00e3o direta e, de fato, em algumas \u00e1reas, essa rivalidade \u00e9 evidente, como no cr\u00e9dito pessoal e nos meios de pagamento.<\/p>\n\n\n\n<p><strong>Onde h\u00e1 espa\u00e7o para cooperar<\/strong><\/p>\n\n\n\n<p>Apesar dessa tens\u00e3o competitiva, as fintechs n\u00e3o vieram para substituir os bancos, mas para preencher lacunas que as grandes institui\u00e7\u00f5es financeiras deixaram ao longo dos anos. Muitos bancos, inclusive, t\u00eam visto as fintechs como parceiras estrat\u00e9gicas em vez de competidoras. Isso \u00e9 evidenciado pelo n\u00famero crescente de colabora\u00e7\u00f5es, aquisi\u00e7\u00f5es e parcerias entre os dois lados.<\/p>\n\n\n\n<p>Hoje, grande parte dos bancos tradicionais no Brasil j\u00e1 est\u00e3o envolvidos em algum tipo de coopera\u00e7\u00e3o com fintechs. H\u00e1 exemplos cl\u00e1ssicos que s\u00e3o grandes cases de sucesso no Brasil, como o Cubo, hub de inova\u00e7\u00e3o do Ita\u00fa, e o Inovabra, do Bradesco Estes espa\u00e7os buscam conectar a estrutura dos grandes bancos com o ecossistema latente das startups. A explica\u00e7\u00e3o \u00e9 simples: as fintechs s\u00e3o especialistas em inova\u00e7\u00e3o e agilidade, enquanto os bancos tradicionais trazem escala, experi\u00eancia regulat\u00f3ria e uma vasta base de clientes. Um bom exemplo de colabora\u00e7\u00e3o bem sucedida \u00e9 a da pr\u00f3pria Trademaster, fintech que fundei, que conta com a Sofisa e o banco BV como investidores s\u00f3cio-propriet\u00e1rios.<\/p>\n\n\n\n<p>Tamb\u00e9m \u00e9 destaque nesta rela\u00e7\u00e3o, a coopera\u00e7\u00e3o na implementa\u00e7\u00e3o do Open Banking, que foi oficialmente lan\u00e7ado no Brasil em 2021. Esse sistema, que permite o compartilhamento de dados banc\u00e1rios entre diferentes institui\u00e7\u00f5es financeiras com o consentimento do cliente, \u00e9 uma oportunidade clara para bancos e fintechs trabalharem juntos. Enquanto as fintechs podem desenvolver solu\u00e7\u00f5es customizadas para os clientes, os bancos podem usar sua infraestrutura para garantir a seguran\u00e7a e a conformidade regulat\u00f3ria.<\/p>\n\n\n\n<p>No entanto, a coopera\u00e7\u00e3o entre bancos e fintechs n\u00e3o \u00e9 isenta de desafios. A diferen\u00e7a cultural entre as duas partes pode ser um obst\u00e1culo. Bancos tradicionais s\u00e3o, por natureza, mais conservadores e regulados, enquanto as fintechs tendem a valorizar a inova\u00e7\u00e3o r\u00e1pida e uma abordagem mais flex\u00edvel. Equilibrar essas duas abordagens \u00e9 fundamental para o sucesso de parcerias.<\/p>\n\n\n\n<p>Al\u00e9m disso, quest\u00f5es relacionadas \u00e0 regula\u00e7\u00e3o e seguran\u00e7a de dados permanecem no centro do debate. Embora o Banco Central tenha avan\u00e7ado com regulamenta\u00e7\u00f5es como o Open Banking e o PIX, ainda h\u00e1 d\u00favidas sobre como garantir que essas novas solu\u00e7\u00f5es sejam seguras e acess\u00edveis a todos os brasileiros. As fintechs t\u00eam uma abordagem mais din\u00e2mica, o que as torna mais propensas a experimentar novas tecnologias e modelos de neg\u00f3cio. J\u00e1 os bancos precisam seguir protocolos de seguran\u00e7a muito r\u00edgidos, o que pode desacelerar o processo de integra\u00e7\u00e3o de inova\u00e7\u00f5es.<\/p>\n\n\n\n<p>Diante desse cen\u00e1rio, acredito que a coopera\u00e7\u00e3o entre bancos e fintechs ser\u00e1 cada vez mais a norma no Brasil. As fintechs s\u00e3o importantes catalisadoras de inova\u00e7\u00e3o, mas os bancos continuam a ter um papel fundamental na estabilidade e seguran\u00e7a do sistema financeiro. Ao combinar as for\u00e7as de ambos os lados, \u00e9 poss\u00edvel criar um ecossistema financeiro mais inclusivo, eficiente e din\u00e2mico. Ao inv\u00e9s de rivais, bancos e fintechs podem, e devem, ser parceiros na cria\u00e7\u00e3o de um novo futuro financeiro para o Brasil.<\/p>\n\n\n\n<p><strong><em>*Formado em Administra\u00e7\u00e3o pela FGV (Funda\u00e7\u00e3o Get\u00falio Vargas) e especialista em solu\u00e7\u00f5es de cr\u00e9dito para as pequenas e m\u00e9dias empresas, Francisco Pereira \u00e9 fundador e CEO da Trademaster, fintech que potencializa as vendas de grandes ind\u00fastrias e distribuidores ao varejo.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por\u00a0Francisco Pereira, CEO da\u00a0Trademaster* Nos \u00faltimos anos, o mercado financeiro brasileiro passou por uma transforma\u00e7\u00e3o acelerada, impulsionada pelo surgimento e crescimento das&#8230;<\/p>\n","protected":false},"author":34,"featured_media":57763,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2160],"tags":[],"ppma_author":[13241],"class_list":{"0":"post-58115","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-financas"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir? - Economia S\/A<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir? - Economia S\/A\" \/>\n<meta property=\"og:description\" content=\"Por\u00a0Francisco Pereira, CEO da\u00a0Trademaster* Nos \u00faltimos anos, o mercado financeiro brasileiro passou por uma transforma\u00e7\u00e3o acelerada, impulsionada pelo surgimento e crescimento das...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/\" \/>\n<meta property=\"og:site_name\" content=\"Economia S\/A\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-27T17:54:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T17:54:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad\"},\"headline\":\"Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir?\",\"datePublished\":\"2025-03-27T17:54:40+00:00\",\"dateModified\":\"2025-03-27T17:54:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/\"},\"wordCount\":980,\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-scaled.jpg\",\"articleSection\":[\"Finan\u00e7as\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/\",\"url\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/\",\"name\":\"Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir? - Economia S\/A\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-scaled.jpg\",\"datePublished\":\"2025-03-27T17:54:40+00:00\",\"dateModified\":\"2025-03-27T17:54:41+00:00\",\"author\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad\"},\"breadcrumb\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#primaryimage\",\"url\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-scaled.jpg\",\"contentUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-scaled.jpg\",\"width\":2560,\"height\":1685},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/economiasa.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\",\"url\":\"https:\/\/economiasa.com.br\/blog\/\",\"name\":\"Economia S\/A\",\"description\":\"Ler faz bem para os neg\u00f3cios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g95c45ea7f8b68489539e6695756c62d9\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\/\/economiasa.com.br\/blog\/author\/fada\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir? - Economia S\/A","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/","og_locale":"pt_BR","og_type":"article","og_title":"Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir? - Economia S\/A","og_description":"Por\u00a0Francisco Pereira, CEO da\u00a0Trademaster* Nos \u00faltimos anos, o mercado financeiro brasileiro passou por uma transforma\u00e7\u00e3o acelerada, impulsionada pelo surgimento e crescimento das...","og_url":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/","og_site_name":"Economia S\/A","article_published_time":"2025-03-27T17:54:40+00:00","article_modified_time":"2025-03-27T17:54:41+00:00","og_image":[{"width":2560,"height":1685,"url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-scaled.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#article","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad"},"headline":"Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir?","datePublished":"2025-03-27T17:54:40+00:00","dateModified":"2025-03-27T17:54:41+00:00","mainEntityOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/"},"wordCount":980,"image":{"@id":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-scaled.jpg","articleSection":["Finan\u00e7as"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/","url":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/","name":"Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir? - Economia S\/A","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#primaryimage"},"image":{"@id":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-scaled.jpg","datePublished":"2025-03-27T17:54:40+00:00","dateModified":"2025-03-27T17:54:41+00:00","author":{"@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad"},"breadcrumb":{"@id":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#primaryimage","url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-scaled.jpg","contentUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/03\/Francisco-Pereira-CEO-Trademaster-2_divulgacao-min-1-scaled.jpg","width":2560,"height":1685},{"@type":"BreadcrumbList","@id":"https:\/\/economiasa.com.br\/blog\/bancos-e-fintechs-e-possivel-cooperar-sem-competir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/economiasa.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Bancos e fintechs: \u00e9 poss\u00edvel cooperar sem competir?"}]},{"@type":"WebSite","@id":"https:\/\/economiasa.com.br\/blog\/#website","url":"https:\/\/economiasa.com.br\/blog\/","name":"Economia S\/A","description":"Ler faz bem para os neg\u00f3cios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g95c45ea7f8b68489539e6695756c62d9","url":"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/economiasa.com.br\/blog\/author\/fada\/"}]}},"authors":[{"term_id":13241,"user_id":34,"is_guest":0,"slug":"fada","display_name":"Reda\u00e7\u00e3o","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/58115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/comments?post=58115"}],"version-history":[{"count":0,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/58115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media\/57763"}],"wp:attachment":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media?parent=58115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/categories?post=58115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/tags?post=58115"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/ppma_author?post=58115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}