{"id":63170,"date":"2025-06-20T13:18:14","date_gmt":"2025-06-20T16:18:14","guid":{"rendered":"https:\/\/economiasa.com.br\/blog\/?p=63170"},"modified":"2025-06-20T13:18:15","modified_gmt":"2025-06-20T16:18:15","slug":"visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2","status":"publish","type":"post","link":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/","title":{"rendered":"Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"626\" src=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-1024x626.jpg\" alt=\"Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro - Divulga\u00e7\u00e3o\" class=\"wp-image-57311\" srcset=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-1024x626.jpg 1024w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-300x184.jpg 300w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-768x470.jpg 768w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-1536x940.jpg 1536w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-2048x1253.jpg 2048w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-360x220.jpg 360w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro \u2013 Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p><em>Com a expans\u00e3o da capacidade produtiva, a foodtech poder\u00e1 produzir at\u00e9 5 toneladas mensais do ingrediente Neutra PRO<\/em><\/p>\n\n\n\n<p>A\u00a0<a href=\"https:\/\/typcal.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Typcal<\/strong><\/a>, primeira\u00a0<em>foodtech\u00a0<\/em>da Am\u00e9rica Latina a trabalhar com fermenta\u00e7\u00e3o de mic\u00e9lios, se uniu \u00e0\u00a0<a href=\"https:\/\/www.allbiom.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Allbiom<\/a>, empresa nacional especializada em produ\u00e7\u00e3o de biorreatores, para construir a primeira f\u00e1brica de fermenta\u00e7\u00e3o de mic\u00e9lio para alimentos no mercado latino-americano. Essa parceria representa um avan\u00e7o na expans\u00e3o da capacidade produtiva do ingrediente\u00a0<strong>Neutra PRO<\/strong>, \u00fanica prote\u00edna sem sabor residual, desenvolvida a partir da economia circular. Com a inaugura\u00e7\u00e3o prevista para o terceiro trimestre de 2025, a nova unidade da Typcal permitir\u00e1 a produ\u00e7\u00e3o de at\u00e9 5 toneladas por m\u00eas da solu\u00e7\u00e3o. Para o primeiro ano de opera\u00e7\u00e3o da nova f\u00e1brica, a empresa projeta um faturamento de aproximadamente R$ 5 milh\u00f5es, com um crescimento estimado de 10 vezes para 2026.\u00a0<\/p>\n\n\n\n<p>\u201cGanhamos um parceiro estrat\u00e9gico que pode nos apoiar tanto no aprimoramento tecnol\u00f3gico, quanto a atingir escala industrial. Juntos trabalharemos em otimiza\u00e7\u00e3o de processos e equipamentos, posicionando as duas empresas como refer\u00eancias neste mercado globalmente. Isso est\u00e1 nos permitindo sair de uma planta-piloto, utilizada para valida\u00e7\u00e3o da tecnologia e testes com a ind\u00fastria, para uma opera\u00e7\u00e3o em expans\u00e3o, pronta para atender clientes que buscam agregar saudabilidade e sustentabilidade aos seus produtos\u201d, destaca Eduardo Sydney, CTO da Typcal.<\/p>\n\n\n\n<p>Com a amplia\u00e7\u00e3o da f\u00e1brica, a foodtech se consolida como o maior e primeiro player da Am\u00e9rica Latina em fermenta\u00e7\u00e3o de mic\u00e9lio e um dos mais inovadores do mundo em termos de tecnologia, j\u00e1 tendo figurado por 2 anos consecutivos na lista Foodtech 500, lista que contempla as empresas mais inovadoras do segmento globalmente atendendo \u00e0s demandas da ind\u00fastria por ingredientes mais saud\u00e1veis e sustent\u00e1veis. Al\u00e9m de refor\u00e7ar sua posi\u00e7\u00e3o no mercado, a empresa redefine os padr\u00f5es de produ\u00e7\u00e3o de prote\u00ednas, uma vez que a planta produtiva gera mais prote\u00edna por metro quadrado do que qualquer outra fonte dispon\u00edvel, seja animal ou vegetal. A t\u00edtulo de exemplo, mesmo comparado com soja s\u00e3o 7.000x mais prote\u00edna por metro quadrado.<\/p>\n\n\n\n<p>\u201cPara a Allbiom, que sempre est\u00e1 em busca de novas tecnologias e estar na vanguarda do mercado de biotecnologia, essa parceria faz todo sentido. Somos a primeira empresa brasileira a trabalhar exclusivamente com bioprocessos e sempre visamos diversificar as aplica\u00e7\u00f5es de nossas solu\u00e7\u00f5es, Por isso queremos estar no mercado de\u00a0<em>foodtechs<\/em>, auxiliando a Typcal a consolidar a sua tecnologia.\u201d destaca Wladimir Grau, diretor comercial da Allbiom.<\/p>\n\n\n\n<p>A expans\u00e3o tamb\u00e9m acelera a entrada da\u00a0<em>foodtech\u00a0<\/em>em mercados internacionais. \u201cNosso ingrediente j\u00e1 \u00e9 aprovado em outros continentes, como Europeu,pa\u00edses, o que facilita a exporta\u00e7\u00e3o. Al\u00e9m disso, a expans\u00e3o no Brasil passa a ser um primeiro passo para a constru\u00e7\u00e3o de f\u00e1bricas em outros continentes\u201d, afirma Paulo Ibri, CEO da Typcal.<\/p>\n\n\n\n<p>Visando inovar cada vez mais e se tornar pioneira no segmento, a\u00a0<em>foodtech\u00a0<\/em>tamb\u00e9m continuar\u00e1 investindo em pesquisa e desenvolvimento para levar ao mercado novas solu\u00e7\u00f5es \u00e0 base de fermenta\u00e7\u00e3o, fortalecendo sua lideran\u00e7a no setor ao promover ingredientes que podem ser aplicados em diversos segmentos de produto e com m\u00faltiplas funcionalidades mais saud\u00e1veis para as pessoas e sustent\u00e1veis para o planeta.<\/p>\n\n\n\n<p><strong>Sobre a Typcal:\u00a0<\/strong><\/p>\n\n\n\n<p>A Typcal, primeira\u00a0<em>foodtech\u00a0<\/em>da Am\u00e9rica Latina a desenvolver fermenta\u00e7\u00e3o de mic\u00e9lio por meio da economia circular, criou um novo ingrediente para a ind\u00fastria aliment\u00edcia. Atrav\u00e9s da Com biotecnologia, a empresa desenvolveu um processo escal\u00e1vel e sustent\u00e1vel para produzir prote\u00edna \u00e0 base de mic\u00e9lio, que pode ser usado em diferentes produtos aliment\u00edcios e promover mais sa\u00fade para as pessoas e sustentabilidade para o planeta. A\u00a0<em>foodtech<\/em>, que ir\u00e1 expandir de f\u00e1brica piloto para comercial no meio de 2025 e iniciar a abertura do mercado europeu, est\u00e1 buscando parcerias com grandes multinacionais para aumentar seu portf\u00f3lio, al\u00e9m de prever um lan\u00e7amento de produto para o primeiro quarter de 2025. Em 2025, pelo segundo ano consecutivo, a empresa entrou no ranking Foodtech 500, \u00edndice global que lista as empresas mais inovadoras do setor. Atualmente, a empresa conta com dois investidores reconhecidos no cen\u00e1rio esportivo: o ex-jogador de v\u00f4lei e treinador da sele\u00e7\u00e3o brasileira, Bernardinho, e o jogador de v\u00f4lei Bruninho. Saiba mais no\u00a0<a href=\"https:\/\/typcal.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">site<\/a>.<\/p>\n\n\n\n<p><strong>Sobre a Allbiom:<\/strong><\/p>\n\n\n\n<p>Fundada em 2012, a Allbiom foi criada devido \u00e0 falta de empresas nacionais especialistas em bioprocessos. O engenheiro de bioprocessos Ricardo Assmann trabalhava na Ourofino Sa\u00fade Animal e sentiu a falta de fornecedores que pudessem atender com qualidade na entrega de biorreatores e assist\u00eancia t\u00e9cnica. Seu futuro s\u00f3cio, Wladimir Crancianinov, trabalhava numa multinacional que importava esses equipamentos, e aceitou o convite de Assmann por entender que as empresas de fora do Brasil n\u00e3o atendiam de maneira customizada o mercado brasileiro.\u00a0<\/p>\n\n\n\n<p>Depois de atingido o objetivo inicial de comercializar biorreatores, a Allbiom ampliou sua atua\u00e7\u00e3o, com a presta\u00e7\u00e3o de servi\u00e7os dentro de sua unidade fabril. J\u00e1 com mais um s\u00f3cio na empresa, Jo\u00e3o Neto, a Allbiom fabricou e instalou na sua pr\u00f3pria unidade uma biof\u00e1brica com intuito de ser um show-room da Allbiom, um local de terceiriza\u00e7\u00e3o de produ\u00e7\u00e3o para seus clientes, um espa\u00e7o para pesquisa e desenvolvimento de novas tecnologias para o mercado, seja nos equipamentos ou nos bioinsumos. A empresa tamb\u00e9m abriu um novo bra\u00e7o educacional, com cursos presenciais e on-line de capacita\u00e7\u00e3o de profissionais que visam trabalhar em ind\u00fastrias de biotecnologia. Saiba mais no\u00a0<a href=\"http:\/\/www.allbiom.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">site<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a expans\u00e3o da capacidade produtiva, a foodtech poder\u00e1 produzir at\u00e9 5 toneladas mensais do ingrediente Neutra PRO A\u00a0Typcal, primeira\u00a0foodtech\u00a0da Am\u00e9rica Latina&#8230;<\/p>\n","protected":false},"author":34,"featured_media":57311,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,101],"tags":[],"ppma_author":[13241],"class_list":{"0":"post-63170","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-business","8":"category-negocios"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio - Economia S\/A<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio - Economia S\/A\" \/>\n<meta property=\"og:description\" content=\"Com a expans\u00e3o da capacidade produtiva, a foodtech poder\u00e1 produzir at\u00e9 5 toneladas mensais do ingrediente Neutra PRO A\u00a0Typcal, primeira\u00a0foodtech\u00a0da Am\u00e9rica Latina...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Economia S\/A\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-20T16:18:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T16:18:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad\"},\"headline\":\"Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio\",\"datePublished\":\"2025-06-20T16:18:14+00:00\",\"dateModified\":\"2025-06-20T16:18:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/\"},\"wordCount\":994,\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-scaled.jpg\",\"articleSection\":[\"Business\",\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/\",\"url\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/\",\"name\":\"Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio - Economia S\/A\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-scaled.jpg\",\"datePublished\":\"2025-06-20T16:18:14+00:00\",\"dateModified\":\"2025-06-20T16:18:15+00:00\",\"author\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad\"},\"breadcrumb\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#primaryimage\",\"url\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-scaled.jpg\",\"contentUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-scaled.jpg\",\"width\":2560,\"height\":1566,\"caption\":\"Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro - Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/economiasa.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\",\"url\":\"https:\/\/economiasa.com.br\/blog\/\",\"name\":\"Economia S\/A\",\"description\":\"Ler faz bem para os neg\u00f3cios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g95c45ea7f8b68489539e6695756c62d9\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\/\/economiasa.com.br\/blog\/author\/fada\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio - Economia S\/A","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio - Economia S\/A","og_description":"Com a expans\u00e3o da capacidade produtiva, a foodtech poder\u00e1 produzir at\u00e9 5 toneladas mensais do ingrediente Neutra PRO A\u00a0Typcal, primeira\u00a0foodtech\u00a0da Am\u00e9rica Latina...","og_url":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/","og_site_name":"Economia S\/A","article_published_time":"2025-06-20T16:18:14+00:00","article_modified_time":"2025-06-20T16:18:15+00:00","og_image":[{"width":2560,"height":1566,"url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-scaled.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#article","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad"},"headline":"Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio","datePublished":"2025-06-20T16:18:14+00:00","dateModified":"2025-06-20T16:18:15+00:00","mainEntityOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/"},"wordCount":994,"image":{"@id":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-scaled.jpg","articleSection":["Business","Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/","url":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/","name":"Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio - Economia S\/A","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#primaryimage"},"image":{"@id":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-scaled.jpg","datePublished":"2025-06-20T16:18:14+00:00","dateModified":"2025-06-20T16:18:15+00:00","author":{"@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad"},"breadcrumb":{"@id":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#primaryimage","url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-scaled.jpg","contentUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/02\/Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro-DIVULGACAO4-1-scaled.jpg","width":2560,"height":1566,"caption":"Eduardo-Sydney-e-Paulo-Ibri_Credito-da-imagem-Marcelo-Ribeiro - Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/economiasa.com.br\/blog\/visando-crescer-10x-em-2026-typcal-se-une-a-allbiom-e-construira-primeira-fabrica-da-america-latina-de-fermentacao-de-micelio-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/economiasa.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Visando crescer 10x em 2026, Typcal se une a Allbiom e construir\u00e1 primeira f\u00e1brica da Am\u00e9rica Latina de fermenta\u00e7\u00e3o de mic\u00e9lio"}]},{"@type":"WebSite","@id":"https:\/\/economiasa.com.br\/blog\/#website","url":"https:\/\/economiasa.com.br\/blog\/","name":"Economia S\/A","description":"Ler faz bem para os neg\u00f3cios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/3bb89ffdf33fd4e8b02d5b6eea9ca3ad","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g95c45ea7f8b68489539e6695756c62d9","url":"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/economiasa.com.br\/blog\/author\/fada\/"}]}},"authors":[{"term_id":13241,"user_id":34,"is_guest":0,"slug":"fada","display_name":"Reda\u00e7\u00e3o","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/4f2972f62de6885dcca429ac19cedb2f2cc29059d11fb856e3913b167913f851?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/63170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/comments?post=63170"}],"version-history":[{"count":0,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/63170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media\/57311"}],"wp:attachment":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media?parent=63170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/categories?post=63170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/tags?post=63170"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/ppma_author?post=63170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}