{"id":71437,"date":"2025-10-27T11:43:25","date_gmt":"2025-10-27T14:43:25","guid":{"rendered":"https:\/\/economiasa.com.br\/blog\/?p=71437"},"modified":"2025-10-27T11:43:27","modified_gmt":"2025-10-27T14:43:27","slug":"sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo","status":"publish","type":"post","link":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/","title":{"rendered":"Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1--1024x683.jpg\" alt=\"Divulga\u00e7\u00e3o\/Sicredi\" class=\"wp-image-71438\" srcset=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1--1024x683.jpg 1024w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1--300x200.jpg 300w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1--768x512.jpg 768w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1--1536x1024.jpg 1536w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1--360x240.jpg 360w, https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg 1731w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Divulga\u00e7\u00e3o\/Sicredi<\/figcaption><\/figure>\n\n\n\n<p><em>Institui\u00e7\u00e3o financeira cooperativa refor\u00e7a import\u00e2ncia da consultoria personalizada para investidores de acordo com seus momentos de vida financeira<\/em><\/p>\n\n\n\n<p>Com foco na integra\u00e7\u00e3o, na atualiza\u00e7\u00e3o t\u00e9cnica e no planejamento estrat\u00e9gico, o Summit Investimentos Sicredi 2025 reuniu profissionais da \u00e1rea de investimentos das cooperativas Sicredi que atuam no Paran\u00e1, S\u00e3o Paulo, Rio de Janeiro e parte de Santa Catarina para tr\u00eas dias de imers\u00e3o na sede da B3, em S\u00e3o Paulo. O encontro aconteceu entre os dias 14 e 16 de outubro e destacou o papel essencial dos gerentes e assessores de investimento na jornada do associado, refor\u00e7ando o compromisso com a forma\u00e7\u00e3o cont\u00ednua e com a entrega de uma assessoria financeira cada vez mais pr\u00f3xima e qualificada.<\/p>\n\n\n\n<p>A iniciativa faz parte da agenda permanente de capacita\u00e7\u00e3o da institui\u00e7\u00e3o financeira cooperativa, que busca preparar os profissionais para refor\u00e7ar a postura consultiva e o relacionamento pr\u00f3ximo aos associados na gest\u00e3o de investimentos. Para a gerente de Desenvolvimento de Neg\u00f3cios da Central Sicredi PR\/SP\/RJ, Adriana Zandon\u00e1, o Summit foi um marco de alinhamento e inspira\u00e7\u00e3o. \u201cO objetivo \u00e9 olhar para 2026 sempre focados na trajet\u00f3ria \u00fanica de cada associado. Nosso grande prop\u00f3sito \u00e9 apoi\u00e1-lo na constru\u00e7\u00e3o dos seus sonhos \u2014 e, para isso, precisamos de uma equipe preparada, t\u00e9cnica e com conhecimento\u201d, destacou a mediadora do evento.<\/p>\n\n\n\n<p><strong>Cen\u00e1rio econ\u00f4mico e relacionamento humano<\/strong><\/p>\n\n\n\n<p>A abertura do Summit teve como destaque a palestra \u201cCen\u00e1rio Econ\u00f4mico e Tend\u00eancias para 2026\u201d, conduzida por Eleonora de Oliveira, da equipe de An\u00e1lises Econ\u00f4micas do Sicredi. A economista apresentou dados sobre o mercado financeiro nacional e internacional, com foco na geopol\u00edtica e nos impactos sobre a economia global e brasileira. \u201cA economia brasileira tem tido bom desempenho, mas come\u00e7a a perder tra\u00e7\u00e3o devido aos juros elevados. Nesses momentos de incerteza, o cooperativismo \u2014 especialmente o Sicredi \u2014 tem a vantagem de conhecer de perto o associado e mitigar riscos que outras institui\u00e7\u00f5es n\u00e3o conseguem\u201d, explicou Eleonora.<\/p>\n\n\n\n<p>Na sequ\u00eancia, o gerente de Comunica\u00e7\u00e3o e Marketing da Central Sicredi PR\/SP\/RJ, Rog\u00e9rio Leal, ministrou a palestra \u201cRelacionamento humano em tempos digitais\u201d, refor\u00e7ando a import\u00e2ncia da empatia e da personaliza\u00e7\u00e3o no contato com os associados. \u201cNeste mundo cada vez mais tecnol\u00f3gico, onde a disputa pela aten\u00e7\u00e3o das pessoas \u00e9 intensa, \u00e9 fundamental evitar solu\u00e7\u00f5es prontas e investir em customiza\u00e7\u00e3o \u2014 como eventos especiais para investidores, comunica\u00e7\u00f5es personalizadas e foco no contato humano. Esse \u00e9 o caminho para construir v\u00ednculos mais verdadeiros\u201d, destacou Leal.<\/p>\n\n\n\n<p>O primeiro dia contou com tr\u00eas momentos de discuss\u00e3o sobre estrat\u00e9gias de investimento. Eduardo Crawshaw d\u00b4Azevedo, gerente de Neg\u00f3cios de Investimentos e Previd\u00eancia do Sicredi, apresentou a palestra \u201cVis\u00e3o Alongada na \u00c1rea de Investimentos\u201d. Em seguida, Luiz Furlani (Sicredi Asset), Getulio Ost (Sulam\u00e9rica Asset) e Christopher Smith (Capit\u00e2nia Asset) debateram como alinhar seguran\u00e7a e personaliza\u00e7\u00e3o na jornada do investidor.<\/p>\n\n\n\n<p>\u201cO pr\u00f3ximo ano ser\u00e1 interessante, desafiador e exigente, mas tamb\u00e9m repleto de boas oportunidades para retornos e novos investimentos\u201d, afirmou Andr\u00e9 Salgado, da Adam Capital, que participou do painel \u201cMultimercado em Movimento\u201d ao lado de Furlani e Ost.\u00a0<\/p>\n\n\n\n<p><strong>Educa\u00e7\u00e3o financeira e uso de dados<\/strong><\/p>\n\n\n\n<p>O segundo dia do evento foi dedicado a temas pr\u00e1ticos sobre o papel dos assessores e gerentes na orienta\u00e7\u00e3o financeira e no uso de dados para apoiar o associado investidor. Sandro da Cunha Yamada, analista s\u00eanior de investimentos e previd\u00eancia da Confedera\u00e7\u00e3o Sicredi, falou sobre como adaptar os produtos financeiros aos diferentes momentos de vida do associado.<\/p>\n\n\n\n<p>Em seguida, os assessores de Desenvolvimento do Cooperativismo da Central PR\/SP\/RJ e do Centro Sul, Altair Carrara e Rodrigo Henrique Muller, conduziram a palestra \u201cOrienta\u00e7\u00e3o financeira como b\u00fassola da jornada\u201d, refor\u00e7ando o papel do Sicredi na forma\u00e7\u00e3o de associados mais conscientes financeiramente. \u201cEssa \u00e9 uma iniciativa que ajuda o associado a se organizar dentro de um planejamento, da poupan\u00e7a e do cr\u00e9dito consciente. Assim, ele conquista seus objetivos e realiza seus sonhos junto com o Sicredi\u201d, afirmou Altair.<\/p>\n\n\n\n<p>O dia seguiu com a apresenta\u00e7\u00e3o de dois cases inspiradores. No primeiro, Fernando Jos\u00e9 de Carvalho (Sicredi Campos Gerais), Beatriz Tellaroli Pereira (Sicredi Morada do Sol) e Rubens Santos da Silva Junior (Sicredi Paranapanema) mostraram o diferencial do cooperativismo no atendimento \u00e0 pessoa f\u00edsica. \u201cTenho muito orgulho e enxergo prop\u00f3sito em atender, porque acredito que podemos mudar a vida do associado por meio da educa\u00e7\u00e3o financeira\u201d, relatou Beatriz Tellaroli Pereira.<\/p>\n\n\n\n<p>O segundo case, \u201cSolu\u00e7\u00f5es financeiras para Pessoa Jur\u00eddica \u2014 Experi\u00eancia de sucesso com empresas locais\u201d, foi apresentado por Jonas Eduardo Davide (Sicredi Agroempresarial), Sandro Roque (Sicredi Grandes Lagos) e Thiago Teixeira Amaral Sneideris (Sicredi Centro Oeste Paulista).<\/p>\n\n\n\n<p>Encerrando o dia, Matheus Charleaux, da B3, apresentou a palestra \u201cComo utilizar os dados para entregar valor na jornada do associado investidor?\u201d, mostrando como a an\u00e1lise de informa\u00e7\u00f5es pode potencializar as estrat\u00e9gias das cooperativas. \u201cEstamos desenvolvendo novas frentes de dados e, o mais importante, queremos estar pr\u00f3ximos e ouvir as cooperativas. O Sicredi nos d\u00e1 essa oportunidade de levar inova\u00e7\u00e3o e intelig\u00eancia de mercado at\u00e9 a ponta\u201d, ressaltou Charleaux.<\/p>\n\n\n\n<p><strong>Prop\u00f3sito e personaliza\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>O terceiro e \u00faltimo dia do evento come\u00e7ou com a palestra de Julio Dami\u00e3o, especialista em finan\u00e7as, que abordou \u201cOs desafios de se tornar um profissional relevante\u201d. Em seguida, o painel \u201cO papel protagonista do assessor na vida do associado\u201d reuniu Andr\u00e9 Alonso Brito (Sicredi Nossa Terra), Julio Cesar Santos Borba (Sicredi Rio Paran\u00e1) e Fernando Thom\u00e9 (Sicredi Vale do Piquiri).<\/p>\n\n\n\n<p>Outro destaque foi o case \u201cSolu\u00e7\u00f5es de investimentos para o Agroneg\u00f3cio \u2014 Impacto na jornada do produtor rural\u201d, com Thais Fernanda A. Hermisdorff Amaral (Sicredi Progresso), Everton Aquino Moreira Rodrigues (Sicredi Credjuris) e Djefferson Rodrigo Anschau (Sicredi Alian\u00e7a). \u201cTivemos um crescimento expressivo na base de associados investidores: nossa carteira passou de 10% no ano passado para 20% este ano. Foi um avan\u00e7o muito positivo\u201d, contou Thais.<\/p>\n\n\n\n<p>O encerramento ficou por conta de Fernando Wissmann, consultor de neg\u00f3cios do Sicredi, com a palestra \u201cNichos de associados: um olhar para al\u00e9m da segmenta\u00e7\u00e3o\u201d, convidando os participantes a repensar o atendimento sob uma \u00f3tica mais humana e personalizada.<\/p>\n\n\n\n<p><strong>Miss\u00e3o cumprida<\/strong><\/p>\n\n\n\n<p>Ao longo de tr\u00eas dias, o Summit Investimentos Sicredi 2025 promoveu uma imers\u00e3o em tend\u00eancias econ\u00f4micas, relacionamento humano, educa\u00e7\u00e3o financeira e inova\u00e7\u00e3o em dados \u2014 pilares que sustentam a atua\u00e7\u00e3o do Sicredi em investimentos.<br><br>Mais do que compartilhar conhecimento, o evento refor\u00e7ou o papel das cooperativas como agentes de transforma\u00e7\u00e3o financeira e social. \u201cOlhar para o futuro \u00e9 tamb\u00e9m reafirmar o nosso prop\u00f3sito: estar ao lado do associado, com empatia, t\u00e9cnica e prop\u00f3sito, ajudando-o a crescer de forma sustent\u00e1vel\u201d, concluiu Adriana Zandon\u00e1.<br><\/p>\n\n\n\n<p><strong><em>Sobre o Sicredi<\/em><\/strong><em>O Sicredi \u00e9 uma institui\u00e7\u00e3o financeira cooperativa comprometida com o crescimento de seus associados e com o desenvolvimento das regi\u00f5es onde atua. Possui um modelo de gest\u00e3o que valoriza a participa\u00e7\u00e3o dos mais de 9,5 milh\u00f5es de associados, que exercem o papel de donos do neg\u00f3cio. Com mais de 3 mil ag\u00eancias, o Sicredi est\u00e1 presente fisicamente em todos os estados brasileiros e no Distrito Federal, disponibilizando uma gama completa de solu\u00e7\u00f5es financeiras e n\u00e3o financeiras.<\/em><\/p>\n\n\n\n<p><em>Site do Sicredi:\u00a0<\/em><a href=\"http:\/\/www.sicredi.com.br\/site\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Clique aqui<\/em><\/a><em>\u00a0<\/em><em><br><\/em><em>Redes Sociais:\u00a0<\/em><a href=\"https:\/\/urldefense.proofpoint.com\/v2\/url?u=https-3A__www.facebook.com_Sicredi_&d=DwMGaQ&c=63k7DFQ5NS45K8Wu5uX9Pd1gEa70c_pznLjIw3OxEiE&r=78reeXSRUHsXRv_X52nVFtqn8imrdAy-e5fJ56Qe6zg&m=xAVwqnVpfVTt2Vu2g1Il31gCoCNxIOeNb-plWVTL0kw&s=JKipJ9HxCcwObJ2cU-F6-Mq2sxBtIbmY5-KGbuh8D5g&e=\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Facebook<\/em><\/a><em>\u00a0|\u00a0<\/em><a href=\"https:\/\/urldefense.com\/v3\/__https:\/instagram.com\/sicredi__;!!HhhKMSGjjQV-!skJJ34UnCvSNLF9kBxQaX6TqdH0BMtQRpPFHxp7r_5HWfNomTgv3CmM6sPd-DuzGX3gRRA$\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Instagram<\/em><\/a><em>\u00a0|\u00a0<\/em><a href=\"https:\/\/urldefense.proofpoint.com\/v2\/url?u=https-3A__twitter.com_sicredi-5Foficial&d=DwMGaQ&c=63k7DFQ5NS45K8Wu5uX9Pd1gEa70c_pznLjIw3OxEiE&r=78reeXSRUHsXRv_X52nVFtqn8imrdAy-e5fJ56Qe6zg&m=xAVwqnVpfVTt2Vu2g1Il31gCoCNxIOeNb-plWVTL0kw&s=rREjz000pYFcmWEEXtLWoXAYGWHjlL0RGR2OhBlfpvg&e=\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Twitter<\/em><\/a><em>\u00a0|\u00a0<\/em><a href=\"https:\/\/urldefense.proofpoint.com\/v2\/url?u=https-3A__www.linkedin.com_company_sicredi&d=DwMGaQ&c=63k7DFQ5NS45K8Wu5uX9Pd1gEa70c_pznLjIw3OxEiE&r=78reeXSRUHsXRv_X52nVFtqn8imrdAy-e5fJ56Qe6zg&m=xAVwqnVpfVTt2Vu2g1Il31gCoCNxIOeNb-plWVTL0kw&s=9Afr_6-_zQljoX3PTOiIuUAk3glYTUttfE8zyudIzKg&e=\" target=\"_blank\" rel=\"noreferrer noopener\"><em>LinkedIn<\/em><\/a><em>\u00a0|\u00a0<\/em><a href=\"https:\/\/urldefense.proofpoint.com\/v2\/url?u=https-3A__www.youtube.com_user_sicredioficial&d=DwMGaQ&c=63k7DFQ5NS45K8Wu5uX9Pd1gEa70c_pznLjIw3OxEiE&r=78reeXSRUHsXRv_X52nVFtqn8imrdAy-e5fJ56Qe6zg&m=xAVwqnVpfVTt2Vu2g1Il31gCoCNxIOeNb-plWVTL0kw&s=gYFE34Op3aDlZfviXJsdbFh5VGFhNtFoc8XmCLM1DTQ&e=\" target=\"_blank\" rel=\"noreferrer noopener\"><em>YouTube<\/em><\/a><em>\u00a0|\u00a0<\/em><a href=\"https:\/\/www.tiktok.com\/@sicredi\" target=\"_blank\" rel=\"noreferrer noopener\"><em>TikTok<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Institui\u00e7\u00e3o financeira cooperativa refor\u00e7a import\u00e2ncia da consultoria personalizada para investidores de acordo com seus momentos de vida financeira Com foco na integra\u00e7\u00e3o,&#8230;<\/p>\n","protected":false},"author":13,"featured_media":71438,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5556],"tags":[],"ppma_author":[13237],"class_list":{"0":"post-71437","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-investimentos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo - Economia S\/A<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo - Economia S\/A\" \/>\n<meta property=\"og:description\" content=\"Institui\u00e7\u00e3o financeira cooperativa refor\u00e7a import\u00e2ncia da consultoria personalizada para investidores de acordo com seus momentos de vida financeira Com foco na integra\u00e7\u00e3o,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/\" \/>\n<meta property=\"og:site_name\" content=\"Economia S\/A\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T14:43:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T14:43:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1731\" \/>\n\t<meta property=\"og:image:height\" content=\"1154\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf\"},\"headline\":\"Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo\",\"datePublished\":\"2025-10-27T14:43:25+00:00\",\"dateModified\":\"2025-10-27T14:43:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/\"},\"wordCount\":1289,\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg\",\"articleSection\":[\"Investimentos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/\",\"url\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/\",\"name\":\"Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo - Economia S\/A\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg\",\"datePublished\":\"2025-10-27T14:43:25+00:00\",\"dateModified\":\"2025-10-27T14:43:27+00:00\",\"author\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf\"},\"breadcrumb\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#primaryimage\",\"url\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg\",\"contentUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg\",\"width\":1731,\"height\":1154,\"caption\":\"Divulga\u00e7\u00e3o\/Sicredi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/economiasa.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\",\"url\":\"https:\/\/economiasa.com.br\/blog\/\",\"name\":\"Economia S\/A\",\"description\":\"Ler faz bem para os neg\u00f3cios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g8b4e5e7107f0781ab9bc60df20107da5\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\/\/economiasa.com.br\/blog\/author\/vhassessoriagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo - Economia S\/A","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/","og_locale":"pt_BR","og_type":"article","og_title":"Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo - Economia S\/A","og_description":"Institui\u00e7\u00e3o financeira cooperativa refor\u00e7a import\u00e2ncia da consultoria personalizada para investidores de acordo com seus momentos de vida financeira Com foco na integra\u00e7\u00e3o,...","og_url":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/","og_site_name":"Economia S\/A","article_published_time":"2025-10-27T14:43:25+00:00","article_modified_time":"2025-10-27T14:43:27+00:00","og_image":[{"width":1731,"height":1154,"url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#article","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf"},"headline":"Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo","datePublished":"2025-10-27T14:43:25+00:00","dateModified":"2025-10-27T14:43:27+00:00","mainEntityOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/"},"wordCount":1289,"image":{"@id":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg","articleSection":["Investimentos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/","url":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/","name":"Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo - Economia S\/A","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#primaryimage"},"image":{"@id":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg","datePublished":"2025-10-27T14:43:25+00:00","dateModified":"2025-10-27T14:43:27+00:00","author":{"@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf"},"breadcrumb":{"@id":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#primaryimage","url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg","contentUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2025\/10\/v2-718f9edd-9aa9-4031-a403-9056dc2ee72a-1-.jpg","width":1731,"height":1154,"caption":"Divulga\u00e7\u00e3o\/Sicredi"},{"@type":"BreadcrumbList","@id":"https:\/\/economiasa.com.br\/blog\/sicredi-organiza-summit-investimentos-na-b3-de-sao-paulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/economiasa.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Sicredi organiza Summit Investimentos na B3 de S\u00e3o Paulo"}]},{"@type":"WebSite","@id":"https:\/\/economiasa.com.br\/blog\/#website","url":"https:\/\/economiasa.com.br\/blog\/","name":"Economia S\/A","description":"Ler faz bem para os neg\u00f3cios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g8b4e5e7107f0781ab9bc60df20107da5","url":"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/economiasa.com.br\/blog\/author\/vhassessoriagmail-com\/"}]}},"authors":[{"term_id":13237,"user_id":13,"is_guest":0,"slug":"vhassessoriagmail-com","display_name":"Reda\u00e7\u00e3o","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/71437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/comments?post=71437"}],"version-history":[{"count":0,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/71437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media\/71438"}],"wp:attachment":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media?parent=71437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/categories?post=71437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/tags?post=71437"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/ppma_author?post=71437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}