{"id":75333,"date":"2026-01-30T12:48:19","date_gmt":"2026-01-30T15:48:19","guid":{"rendered":"https:\/\/economiasa.com.br\/blog\/?p=75333"},"modified":"2026-01-30T12:48:20","modified_gmt":"2026-01-30T15:48:20","slug":"guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste","status":"publish","type":"post","link":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/","title":{"rendered":"Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste"},"content":{"rendered":"\n<p>A Guanabara, empresa do setor de transporte rodovi\u00e1rio, refor\u00e7a sua estrat\u00e9gia de aproxima\u00e7\u00e3o com o p\u00fablico ao marcar presen\u00e7a nos principais eventos pr\u00e9-carnavalescos do Nordeste em 2026. A iniciativa contempla a\u00e7\u00f5es em Fortaleza (CE), Teresina (PI), Natal (RN), Jo\u00e3o Pessoa (PB) e Salvador (BA), integrando a marca a uma das agendas culturais mais relevantes da regi\u00e3o.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o teve in\u00edcio em Teresina, no dia 24 de janeiro, com ativa\u00e7\u00f5es no Bailinho do We All. As a\u00e7\u00f5es combinaram experi\u00eancias de conviv\u00eancia ao ar livre com a din\u00e2mica do carnaval de rua, ampliando o contato da marca com diferentes perfis de p\u00fablico. O destaque agora \u00e9 o Aldebaran Leste Folia 2026, que ser\u00e1 realizado neste s\u00e1bado (31), \u00e0s 19h, abrindo alas para mais uma pr\u00e9via carnavalesca.<\/p>\n\n\n\n<p>Em Fortaleza, a Guanabara acompanhou a movimenta\u00e7\u00e3o do pr\u00e9-carnaval na Praia de Iracema e concentra sua principal ativa\u00e7\u00e3o no primeiro s\u00e1bado de fevereiro (7). As a\u00e7\u00f5es incluem presen\u00e7a no pr\u00e9-carnaval do Liso Bar, na Barraca Santa Praia e no Bloquinho do Badud\u00e9, eventos que integram o circuito cultural da capital cearense neste per\u00edodo.<\/p>\n\n\n\n<p>O roteiro segue para outras capitais nordestinas. Em Natal, no dia 7 de fevereiro, a empresa participa do Bloco do Seu Gentil, na Pra\u00e7a Pedro Velho, a partir das 15h. J\u00e1 em Jo\u00e3o Pessoa, a Guanabara estar\u00e1 presente entre os dias 6 a 11 de fevereiro no Camarote Cabo Branco, um dos principais pontos de encontro da Via Folia. Em Salvador, a marca integra a programa\u00e7\u00e3o do Bloco Q\u2019Nada, que celebra os 110 anos do samba, conectando a ativa\u00e7\u00e3o \u00e0 tradi\u00e7\u00e3o cultural da capital baiana.<\/p>\n\n\n\n<p>Segundo o gerente de marketing da Guanabara, Rodrigo Mont\u2019Alverne, as a\u00e7\u00f5es fazem parte de um planejamento mais amplo para 2026. \u201cA presen\u00e7a da empresa nessas ativa\u00e7\u00f5es marca o in\u00edcio de um ano com projetos relevantes. O pr\u00e9-carnaval \u00e9 um ambiente estrat\u00e9gico para estreitar o relacionamento com o p\u00fablico e antecipar iniciativas que ser\u00e3o apresentadas ao longo dos pr\u00f3ximos meses\u201d, afirma.<\/p>\n\n\n\n<p>As ativa\u00e7\u00f5es integram a estrat\u00e9gia da empresa de fortalecer sua presen\u00e7a institucional no Nordeste, associando a marca a eventos culturais de grande alcance e relev\u00e2ncia regional<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Guanabara, empresa do setor de transporte rodovi\u00e1rio, refor\u00e7a sua estrat\u00e9gia de aproxima\u00e7\u00e3o com o p\u00fablico ao marcar presen\u00e7a nos principais eventos&#8230;<\/p>\n","protected":false},"author":30,"featured_media":75334,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1973],"tags":[],"ppma_author":[13239],"class_list":{"0":"post-75333","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-eventos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste - Economia S\/A<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste - Economia S\/A\" \/>\n<meta property=\"og:description\" content=\"A Guanabara, empresa do setor de transporte rodovi\u00e1rio, refor\u00e7a sua estrat\u00e9gia de aproxima\u00e7\u00e3o com o p\u00fablico ao marcar presen\u00e7a nos principais eventos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/\" \/>\n<meta property=\"og:site_name\" content=\"Economia S\/A\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T15:48:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T15:48:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/01\/Pre-Carnaval-Guanabara-Fortal-4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/a8858b73a9a3b3708989ee3f5bc2e58d\"},\"headline\":\"Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste\",\"datePublished\":\"2026-01-30T15:48:19+00:00\",\"dateModified\":\"2026-01-30T15:48:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/\"},\"wordCount\":398,\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/01\/Pre-Carnaval-Guanabara-Fortal-4.jpeg\",\"articleSection\":[\"Eventos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/\",\"url\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/\",\"name\":\"Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste - Economia S\/A\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/01\/Pre-Carnaval-Guanabara-Fortal-4.jpeg\",\"datePublished\":\"2026-01-30T15:48:19+00:00\",\"dateModified\":\"2026-01-30T15:48:20+00:00\",\"author\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/a8858b73a9a3b3708989ee3f5bc2e58d\"},\"breadcrumb\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#primaryimage\",\"url\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/01\/Pre-Carnaval-Guanabara-Fortal-4.jpeg\",\"contentUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/01\/Pre-Carnaval-Guanabara-Fortal-4.jpeg\",\"width\":1200,\"height\":1600,\"caption\":\"Pre-Carnaval-Guanabara-Fortal - Cr\u00e9ditos da foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/economiasa.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\",\"url\":\"https:\/\/economiasa.com.br\/blog\/\",\"name\":\"Economia S\/A\",\"description\":\"Ler faz bem para os neg\u00f3cios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/a8858b73a9a3b3708989ee3f5bc2e58d\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8d4189e7e49cc8033fbfc5a49f8d73aab9c244e590ce7cb37c5f9749539e7f5a?s=96&d=mm&r=g6a8786e97c6fe8f840f2f78a8345c39d\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8d4189e7e49cc8033fbfc5a49f8d73aab9c244e590ce7cb37c5f9749539e7f5a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8d4189e7e49cc8033fbfc5a49f8d73aab9c244e590ce7cb37c5f9749539e7f5a?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\/\/economiasa.com.br\/blog\/author\/alecsandro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste - Economia S\/A","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/","og_locale":"pt_BR","og_type":"article","og_title":"Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste - Economia S\/A","og_description":"A Guanabara, empresa do setor de transporte rodovi\u00e1rio, refor\u00e7a sua estrat\u00e9gia de aproxima\u00e7\u00e3o com o p\u00fablico ao marcar presen\u00e7a nos principais eventos...","og_url":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/","og_site_name":"Economia S\/A","article_published_time":"2026-01-30T15:48:19+00:00","article_modified_time":"2026-01-30T15:48:20+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/01\/Pre-Carnaval-Guanabara-Fortal-4.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#article","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/a8858b73a9a3b3708989ee3f5bc2e58d"},"headline":"Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste","datePublished":"2026-01-30T15:48:19+00:00","dateModified":"2026-01-30T15:48:20+00:00","mainEntityOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/"},"wordCount":398,"image":{"@id":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/01\/Pre-Carnaval-Guanabara-Fortal-4.jpeg","articleSection":["Eventos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/","url":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/","name":"Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste - Economia S\/A","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#primaryimage"},"image":{"@id":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/01\/Pre-Carnaval-Guanabara-Fortal-4.jpeg","datePublished":"2026-01-30T15:48:19+00:00","dateModified":"2026-01-30T15:48:20+00:00","author":{"@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/a8858b73a9a3b3708989ee3f5bc2e58d"},"breadcrumb":{"@id":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#primaryimage","url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/01\/Pre-Carnaval-Guanabara-Fortal-4.jpeg","contentUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/01\/Pre-Carnaval-Guanabara-Fortal-4.jpeg","width":1200,"height":1600,"caption":"Pre-Carnaval-Guanabara-Fortal - Cr\u00e9ditos da foto: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/economiasa.com.br\/blog\/guanabara-amplia-presenca-no-pre-carnaval-2026-com-ativacoes-em-cinco-capitais-do-nordeste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/economiasa.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Guanabara amplia presen\u00e7a no pr\u00e9-carnaval 2026 com ativa\u00e7\u00f5es em cinco capitais do Nordeste"}]},{"@type":"WebSite","@id":"https:\/\/economiasa.com.br\/blog\/#website","url":"https:\/\/economiasa.com.br\/blog\/","name":"Economia S\/A","description":"Ler faz bem para os neg\u00f3cios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/a8858b73a9a3b3708989ee3f5bc2e58d","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8d4189e7e49cc8033fbfc5a49f8d73aab9c244e590ce7cb37c5f9749539e7f5a?s=96&d=mm&r=g6a8786e97c6fe8f840f2f78a8345c39d","url":"https:\/\/secure.gravatar.com\/avatar\/8d4189e7e49cc8033fbfc5a49f8d73aab9c244e590ce7cb37c5f9749539e7f5a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d4189e7e49cc8033fbfc5a49f8d73aab9c244e590ce7cb37c5f9749539e7f5a?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/economiasa.com.br\/blog\/author\/alecsandro\/"}]}},"authors":[{"term_id":13239,"user_id":30,"is_guest":0,"slug":"alecsandro","display_name":"Reda\u00e7\u00e3o","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/8d4189e7e49cc8033fbfc5a49f8d73aab9c244e590ce7cb37c5f9749539e7f5a?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/75333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/comments?post=75333"}],"version-history":[{"count":0,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/75333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media\/75334"}],"wp:attachment":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media?parent=75333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/categories?post=75333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/tags?post=75333"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/ppma_author?post=75333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}