{"id":77909,"date":"2026-04-06T13:27:07","date_gmt":"2026-04-06T16:27:07","guid":{"rendered":"https:\/\/economiasa.com.br\/blog\/?p=77909"},"modified":"2026-04-06T13:27:07","modified_gmt":"2026-04-06T16:27:07","slug":"andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo","status":"publish","type":"post","link":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/","title":{"rendered":"Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo"},"content":{"rendered":"\n<p><em>A especialista em estrutura\u00e7\u00e3o de equipes comerciais no mercado imobili\u00e1rio, Andressa Machado, ser\u00e1 uma das palestrantes da 2\u00aa edi\u00e7\u00e3o do evento\u00a0Mulheres na Constru\u00e7\u00e3o, que acontece no dia 8 de abril, na matriz da TOTVS, em S\u00e3o Paulo.<\/em><\/p>\n\n\n\n<p>A executiva sobe ao palco \u00e0s 11h com a palestra\u00a0<strong>\u201cConstruindo o Futuro: O Impacto da Lideran\u00e7a Feminina no Setor\u201d<\/strong>, trazendo uma an\u00e1lise sobre como a presen\u00e7a de mulheres em posi\u00e7\u00f5es estrat\u00e9gicas tem influenciado n\u00e3o apenas a gest\u00e3o, mas tamb\u00e9m os resultados das empresas de constru\u00e7\u00e3o civil, incorpora\u00e7\u00e3o e mercado imobili\u00e1rio.<\/p>\n\n\n\n<p>\u00c0 frente da S\u00edsmica, Andressa atua no desenvolvimento estrat\u00e9gico de equipes de vendas e lideran\u00e7as comerciais, acompanhando de perto a evolu\u00e7\u00e3o do setor imobili\u00e1rio brasileiro, especialmente no que diz respeito \u00e0 profissionaliza\u00e7\u00e3o das vendas e \u00e0 necessidade de estruturas mais preparadas para um mercado cada vez mais sofisticado.<\/p>\n\n\n\n<p>Sua participa\u00e7\u00e3o refor\u00e7a uma discuss\u00e3o crescente no setor: o avan\u00e7o da lideran\u00e7a feminina em \u00e1reas historicamente dominadas por homens e o impacto direto dessa transforma\u00e7\u00e3o na cultura organizacional, na tomada de decis\u00e3o e na performance dos neg\u00f3cios. \u201cQuando falamos de lideran\u00e7a feminina, n\u00e3o estamos falando apenas de representatividade, mas de novas formas de pensar estrat\u00e9gia, relacionamento e constru\u00e7\u00e3o de resultados\u201d, afirma Andressa.<\/p>\n\n\n\n<p>Promovido pela TOTVS, o evento re\u00fane executivas de destaque em empresas de infraestrutura, constru\u00e7\u00e3o civil e incorpora\u00e7\u00e3o para discutir temas como lideran\u00e7a, networking, inclus\u00e3o e transforma\u00e7\u00e3o do setor. A programa\u00e7\u00e3o inclui pain\u00e9is e palestras ao longo da manh\u00e3, com encerramento previsto para o in\u00edcio da tarde.<\/p>\n\n\n\n<p>Servi\u00e7o:<\/p>\n\n\n\n<p><strong>Mulheres na Constru\u00e7\u00e3o 2a Edi\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>Data: 08\/04<\/p>\n\n\n\n<p>Hor\u00e1rio: 8h30 \u00e0s 13h<\/p>\n\n\n\n<p>Local: TOTVS \u2013 Av Braz Leme, 1000<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A especialista em estrutura\u00e7\u00e3o de equipes comerciais no mercado imobili\u00e1rio, Andressa Machado, ser\u00e1 uma das palestrantes da 2\u00aa edi\u00e7\u00e3o do evento\u00a0Mulheres na&#8230;<\/p>\n","protected":false},"author":13,"featured_media":75667,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1973],"tags":[],"ppma_author":[13237],"class_list":{"0":"post-77909","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-eventos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo - Economia S\/A<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo - Economia S\/A\" \/>\n<meta property=\"og:description\" content=\"A especialista em estrutura\u00e7\u00e3o de equipes comerciais no mercado imobili\u00e1rio, Andressa Machado, ser\u00e1 uma das palestrantes da 2\u00aa edi\u00e7\u00e3o do evento\u00a0Mulheres na...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/\" \/>\n<meta property=\"og:site_name\" content=\"Economia S\/A\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-06T16:27:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/02\/Screenshot-2026-01-05-at-14.01.14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1870\" \/>\n\t<meta property=\"og:image:height\" content=\"1480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf\"},\"headline\":\"Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo\",\"datePublished\":\"2026-04-06T16:27:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/\"},\"wordCount\":323,\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/02\/Screenshot-2026-01-05-at-14.01.14.jpg\",\"articleSection\":[\"Eventos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/\",\"url\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/\",\"name\":\"Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo - Economia S\/A\",\"isPartOf\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/02\/Screenshot-2026-01-05-at-14.01.14.jpg\",\"datePublished\":\"2026-04-06T16:27:07+00:00\",\"author\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf\"},\"breadcrumb\":{\"@id\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#primaryimage\",\"url\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/02\/Screenshot-2026-01-05-at-14.01.14.jpg\",\"contentUrl\":\"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/02\/Screenshot-2026-01-05-at-14.01.14.jpg\",\"width\":1870,\"height\":1480,\"caption\":\"Andressa Machado, CEO da S\u00edsmica - Cr\u00e9ditos da foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/economiasa.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#website\",\"url\":\"https:\/\/economiasa.com.br\/blog\/\",\"name\":\"Economia S\/A\",\"description\":\"Ler faz bem para os neg\u00f3cios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g8b4e5e7107f0781ab9bc60df20107da5\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\/\/economiasa.com.br\/blog\/author\/vhassessoriagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo - Economia S\/A","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/","og_locale":"pt_BR","og_type":"article","og_title":"Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo - Economia S\/A","og_description":"A especialista em estrutura\u00e7\u00e3o de equipes comerciais no mercado imobili\u00e1rio, Andressa Machado, ser\u00e1 uma das palestrantes da 2\u00aa edi\u00e7\u00e3o do evento\u00a0Mulheres na...","og_url":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/","og_site_name":"Economia S\/A","article_published_time":"2026-04-06T16:27:07+00:00","og_image":[{"width":1870,"height":1480,"url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/02\/Screenshot-2026-01-05-at-14.01.14.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#article","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf"},"headline":"Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo","datePublished":"2026-04-06T16:27:07+00:00","mainEntityOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/"},"wordCount":323,"image":{"@id":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/02\/Screenshot-2026-01-05-at-14.01.14.jpg","articleSection":["Eventos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/","url":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/","name":"Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo - Economia S\/A","isPartOf":{"@id":"https:\/\/economiasa.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#primaryimage"},"image":{"@id":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/02\/Screenshot-2026-01-05-at-14.01.14.jpg","datePublished":"2026-04-06T16:27:07+00:00","author":{"@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf"},"breadcrumb":{"@id":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#primaryimage","url":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/02\/Screenshot-2026-01-05-at-14.01.14.jpg","contentUrl":"https:\/\/economiasa.com.br\/blog\/wp-content\/uploads\/2026\/02\/Screenshot-2026-01-05-at-14.01.14.jpg","width":1870,"height":1480,"caption":"Andressa Machado, CEO da S\u00edsmica - Cr\u00e9ditos da foto: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/economiasa.com.br\/blog\/andressa-machado-fala-em-evento-sobre-lideranca-feminina-na-construcao-civil-em-sao-paulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/economiasa.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Andressa Machado fala em evento sobre lideran\u00e7a feminina na constru\u00e7\u00e3o civil em S\u00e3o Paulo"}]},{"@type":"WebSite","@id":"https:\/\/economiasa.com.br\/blog\/#website","url":"https:\/\/economiasa.com.br\/blog\/","name":"Economia S\/A","description":"Ler faz bem para os neg\u00f3cios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/economiasa.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/economiasa.com.br\/blog\/#\/schema\/person\/57f2dfaf8250a36d041a4e4cf0498faf","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g8b4e5e7107f0781ab9bc60df20107da5","url":"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/economiasa.com.br\/blog\/author\/vhassessoriagmail-com\/"}]}},"authors":[{"term_id":13237,"user_id":13,"is_guest":0,"slug":"vhassessoriagmail-com","display_name":"Reda\u00e7\u00e3o","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/b9a74cf83ab7b387115b660a012a810ba4283a49e2dc1845eacfc09fd7fadd4b?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/77909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/comments?post=77909"}],"version-history":[{"count":0,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/posts\/77909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media\/75667"}],"wp:attachment":[{"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/media?parent=77909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/categories?post=77909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/tags?post=77909"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/economiasa.com.br\/blog\/wp-json\/wp\/v2\/ppma_author?post=77909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}